{"id":6,"count":33,"description":"","link":"https:\/\/komplitrental.com\/blog\/category\/sewa-led\/","name":"Sewa LED","slug":"sewa-led","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/komplitrental.com\/blog\/wp-json\/wp\/v2\/categories\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/komplitrental.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/komplitrental.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/komplitrental.com\/blog\/wp-json\/wp\/v2\/posts?categories=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}